{"id":770,"date":"2024-03-21T09:55:58","date_gmt":"2024-03-21T09:55:58","guid":{"rendered":"http:\/\/aidatransports.local\/?page_id=770"},"modified":"2026-05-06T07:38:35","modified_gmt":"2026-05-06T07:38:35","slug":"ils-nous-ont-fait-confiance","status":"publish","type":"page","link":"https:\/\/aidatransports.com\/aidat2024\/ils-nous-ont-fait-confiance\/","title":{"rendered":"Ils nous ont fait confiance"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"770\" class=\"elementor elementor-770\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d922dfc elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"d922dfc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cb8eb94\" data-id=\"cb8eb94\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd53595 elementor-widget elementor-widget-heading\" data-id=\"bd53595\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ils nous ont fait confiance<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b54a2e elementor-widget elementor-widget-text-editor\" data-id=\"2b54a2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&rsquo;Excellence Op\u00e9rationnelle au Service des Transporteurs<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-26f9a7a elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"26f9a7a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e4d273\" data-id=\"1e4d273\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9e74e72 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"9e74e72\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-59104fc\" data-id=\"59104fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7acca07 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7acca07\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Nos r\u00e9f\u00e9rences<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4086c37 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4086c37\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3376a7a\" data-id=\"3376a7a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a04ea4f elementor-widget elementor-widget-spacer\" data-id=\"a04ea4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-373d7aa elementor-widget elementor-widget-image\" data-id=\"373d7aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"960\" height=\"306\" src=\"https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/Groupe-Mendy-1024x326.png\" class=\"attachment-large size-large wp-image-2189\" alt=\"\" srcset=\"https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/Groupe-Mendy-1024x326.png 1024w, https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/Groupe-Mendy-300x96.png 300w, https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/Groupe-Mendy-768x244.png 768w, https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/Groupe-Mendy.png 1200w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb99987 elementor-widget elementor-widget-spacer\" data-id=\"fb99987\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a54bb6f\" data-id=\"a54bb6f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c92d617 elementor-widget elementor-widget-image\" data-id=\"c92d617\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"362\" height=\"113\" src=\"https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/transports-peyrou.png\" class=\"attachment-large size-large wp-image-2190\" alt=\"\" srcset=\"https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/transports-peyrou.png 362w, https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/transports-peyrou-300x94.png 300w\" sizes=\"(max-width: 362px) 100vw, 362px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6b9f896 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6b9f896\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-90f5978\" data-id=\"90f5978\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a0f644c elementor-widget elementor-widget-spacer\" data-id=\"a0f644c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce170a8 elementor-widget elementor-widget-image\" data-id=\"ce170a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"293\" src=\"https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/azpeitia-logo-1024x312.png\" class=\"attachment-large size-large wp-image-2191\" alt=\"\" srcset=\"https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/azpeitia-logo-1024x312.png 1024w, https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/azpeitia-logo-300x92.png 300w, https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/azpeitia-logo-768x234.png 768w, https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/azpeitia-logo-1536x469.png 1536w, https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/azpeitia-logo.png 1619w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65678c8 elementor-widget elementor-widget-spacer\" data-id=\"65678c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d9de157\" data-id=\"d9de157\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d96c4d0 elementor-widget elementor-widget-image\" data-id=\"d96c4d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"110\" src=\"https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/transports-sallaberry.png\" class=\"attachment-large size-large wp-image-2192\" alt=\"\" srcset=\"https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/transports-sallaberry.png 512w, https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/transports-sallaberry-300x64.png 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-478fef8 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"478fef8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4a86c43\" data-id=\"4a86c43\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-309ff0e elementor-widget elementor-widget-spacer\" data-id=\"309ff0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-449774c elementor-widget elementor-widget-image\" data-id=\"449774c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"868\" height=\"320\" src=\"https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/SBTT.png\" class=\"attachment-large size-large wp-image-2193\" alt=\"\" srcset=\"https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/SBTT.png 868w, https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/SBTT-300x111.png 300w, https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/SBTT-768x283.png 768w\" sizes=\"(max-width: 868px) 100vw, 868px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c54c2f9 elementor-widget elementor-widget-spacer\" data-id=\"c54c2f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e9ec1d5\" data-id=\"e9ec1d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12e66c2 elementor-widget elementor-widget-image\" data-id=\"12e66c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"662\" height=\"370\" src=\"https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/CLAS.png\" class=\"attachment-large size-large wp-image-2195\" alt=\"\" srcset=\"https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/CLAS.png 662w, https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/CLAS-300x168.png 300w\" sizes=\"(max-width: 662px) 100vw, 662px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88bfe13 elementor-widget elementor-widget-text-editor\" data-id=\"88bfe13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>CLAS Transports | CLAS 2 Charentes<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8dd1852 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"8dd1852\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7265fd3\" data-id=\"7265fd3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b86fbe elementor-widget elementor-widget-text-editor\" data-id=\"8b86fbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Et bien plus encore&#8230;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c10b62 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2c10b62\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-74f95f9\" data-id=\"74f95f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b13e73d elementor-widget elementor-widget-heading\" data-id=\"b13e73d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">F.A.Q<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d940943 elementor-widget elementor-widget-text-editor\" data-id=\"d940943\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous avez des questions ? Notre F.A.Q est l\u00e0 pour y r\u00e9pondre.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0eb153 wpr-advanced-accordion-icon-no-box elementor-widget elementor-widget-wpr-advanced-accordion\" data-id=\"f0eb153\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;active_item&quot;:1}\" data-widget_type=\"wpr-advanced-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n            <div class=\"wpr-advanced-accordion\" data-accordion-type=\"accordion\" data-active-index=\"1\" data-accordion-trigger=\"click\" data-interaction-speed=\"0.4\">\n\n\t\t\t\n                \n\t\t\t\t\t<div class=\"wpr-accordion-item-wrap\">\n\t\t\t\t\t\t<button class=\"wpr-acc-button\">\n\t\t\t\t\t\t\t<span class=\"wpr-acc-item-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-title-icon\">\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"wpr-acc-title-text\">AIDA Transports, c'est quoi ?<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-close\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-caret-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-open\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"wpr-acc-panel\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-panel-content\"><p>AIDA Transports propose une solution TMS compl\u00e8te pour la gestion de l'exploitation, y compris la planification graphique, le suivi de l'affr\u00e8tement, la num\u00e9risation des documents de transport, la facturation, le suivi de tr\u00e9sorerie, les statistiques et la gestion du parc. Cette plateforme est enti\u00e8rement personnalisable et peut \u00eatre adapt\u00e9e en fonction de vos besoins sp\u00e9cifiques.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                    <\/div>\n\n                \n\t\t\t\t\t<div class=\"wpr-accordion-item-wrap\">\n\t\t\t\t\t\t<button class=\"wpr-acc-button\">\n\t\t\t\t\t\t\t<span class=\"wpr-acc-item-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-title-icon\">\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"wpr-acc-title-text\">Qu'est-ce qui nous diff\u00e9rencie ?<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-close\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-caret-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-open\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"wpr-acc-panel\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-panel-content\"><p>Ce qui distingue AIDA Transports de ses concurrents, c'est sa capacit\u00e9 \u00e0 s'adapter aux besoins sp\u00e9cifiques de ses clients. AIDA Transports n'impose aucune limite dans son d\u00e9veloppement. Sa flexibilit\u00e9 lui permet de r\u00e9pondre \u00e0 une multitude de demandes, allant de la gestion de l'exploitation \u00e0 la planification graphique, en passant par le suivi de l'affr\u00e8tement, la num\u00e9risation des documents de transport, la facturation, le suivi de tr\u00e9sorerie, les statistiques et la gestion du parc. En offrant une personnalisation totale, AIDA Transports garantit une solution sur mesure pour chaque entreprise, quelles que soient ses exigences.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                    <\/div>\n\n                \n\t\t\t\t\t<div class=\"wpr-accordion-item-wrap\">\n\t\t\t\t\t\t<button class=\"wpr-acc-button\">\n\t\t\t\t\t\t\t<span class=\"wpr-acc-item-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-title-icon\">\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"wpr-acc-title-text\">Pourquoi y a-t-il plusieurs AIDA ?<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-close\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-caret-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-open\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"wpr-acc-panel\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-panel-content\"><p>AIDA Transports est la solution TMS principale, mais elle peut \u00eatre d\u00e9riv\u00e9e sur :<\/p><ul><li>WEB in AIDA<\/li><li>DOC in AIDA<\/li><li>MOBIL'AIDAT<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                    <\/div>\n\n                            <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ac8787 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4ac8787\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c16d4c1\" data-id=\"c16d4c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3be7c7 elementor-widget elementor-widget-heading\" data-id=\"b3be7c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Votre vision, notre cr\u00e9ation.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bdb2819 elementor-widget elementor-widget-heading\" data-id=\"bdb2819\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Votre logiciel sur mesure selon vos demandes !<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28c39e4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"28c39e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e42352e wpr-button-icon-style-inline wpr-button-icon-position-right elementor-widget elementor-widget-wpr-button\" data-id=\"e42352e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\n\t\t\t\n\t\t\n\t\t<div class=\"wpr-button-wrap elementor-clearfix\">\n\t\t<a class=\"wpr-button wpr-button-effect elementor-animation-float\" data-text=\"\" href=\"https:\/\/aidatransports.com\/aidat2024\/contact-2\/\">\n\t\t\t\n\t\t\t<span class=\"wpr-button-content\">\n\t\t\t\t\t\t\t\t\t<span class=\"wpr-button-text\">Contactez-nous<\/span>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/span>\n\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\n\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ils nous ont fait confiance L&rsquo;Excellence Op\u00e9rationnelle au Service des Transporteurs Nos r\u00e9f\u00e9rences CLAS Transports | CLAS 2 Charentes Et bien plus encore&#8230; F.A.Q Vous avez des questions ? Notre F.A.Q est l\u00e0 pour y r\u00e9pondre. AIDA Transports, c&rsquo;est quoi ? AIDA Transports propose une solution TMS compl\u00e8te pour la gestion de l&rsquo;exploitation, y compris la planification graphique, le suivi de l&rsquo;affr\u00e8tement, la num\u00e9risation des documents de transport, la facturation, le suivi de tr\u00e9sorerie, les statistiques et la gestion du parc. Cette plateforme est enti\u00e8rement personnalisable et peut \u00eatre adapt\u00e9e en fonction de vos besoins sp\u00e9cifiques. Qu&rsquo;est-ce qui nous diff\u00e9rencie ? Ce qui distingue AIDA Transports de ses concurrents, c&rsquo;est sa capacit\u00e9 \u00e0 s&rsquo;adapter aux besoins sp\u00e9cifiques de ses clients. AIDA Transports n&rsquo;impose aucune limite dans son d\u00e9veloppement. Sa flexibilit\u00e9 lui permet de r\u00e9pondre \u00e0 une multitude de demandes, allant de la gestion de l&rsquo;exploitation \u00e0 la planification graphique, en passant par le suivi de l&rsquo;affr\u00e8tement, la num\u00e9risation des documents de transport, la facturation, le suivi de tr\u00e9sorerie, les statistiques et la gestion du parc. En offrant une personnalisation totale, AIDA Transports garantit une solution sur mesure pour chaque entreprise, quelles que soient ses exigences. Pourquoi y a-t-il plusieurs AIDA ? AIDA Transports est la solution TMS principale, mais elle peut \u00eatre d\u00e9riv\u00e9e sur : WEB in AIDA DOC in AIDA MOBIL&rsquo;AIDAT Votre vision, notre cr\u00e9ation. Votre logiciel sur mesure selon vos demandes ! Contactez-nous<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-770","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AIDA Transports | Partenaires<\/title>\n<meta name=\"description\" content=\"Ils nous ont fait confiance. Les partenaires d&#039;AIDA Transports.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aidatransports.com\/aidat2024\/ils-nous-ont-fait-confiance\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AIDA Transports | Partenaires\" \/>\n<meta property=\"og:description\" content=\"Ils nous ont fait confiance. Les partenaires d&#039;AIDA Transports.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aidatransports.com\/aidat2024\/ils-nous-ont-fait-confiance\/\" \/>\n<meta property=\"og:site_name\" content=\"aidatransports\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T07:38:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/Groupe-Mendy.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"382\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aidatransports.com\\\/aidat2024\\\/ils-nous-ont-fait-confiance\\\/\",\"url\":\"https:\\\/\\\/aidatransports.com\\\/aidat2024\\\/ils-nous-ont-fait-confiance\\\/\",\"name\":\"AIDA Transports | Partenaires\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aidatransports.com\\\/aidat2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aidatransports.com\\\/aidat2024\\\/ils-nous-ont-fait-confiance\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aidatransports.com\\\/aidat2024\\\/ils-nous-ont-fait-confiance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aidatransports.com\\\/aidat2024\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Groupe-Mendy-1024x326.png\",\"datePublished\":\"2024-03-21T09:55:58+00:00\",\"dateModified\":\"2026-05-06T07:38:35+00:00\",\"description\":\"Ils nous ont fait confiance. Les partenaires d'AIDA Transports.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aidatransports.com\\\/aidat2024\\\/ils-nous-ont-fait-confiance\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aidatransports.com\\\/aidat2024\\\/ils-nous-ont-fait-confiance\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aidatransports.com\\\/aidat2024\\\/ils-nous-ont-fait-confiance\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aidatransports.com\\\/aidat2024\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Groupe-Mendy.png\",\"contentUrl\":\"https:\\\/\\\/aidatransports.com\\\/aidat2024\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Groupe-Mendy.png\",\"width\":1200,\"height\":382},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aidatransports.com\\\/aidat2024\\\/ils-nous-ont-fait-confiance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/aidatransports.com\\\/aidat2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ils nous ont fait confiance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aidatransports.com\\\/aidat2024\\\/#website\",\"url\":\"https:\\\/\\\/aidatransports.com\\\/aidat2024\\\/\",\"name\":\"aidatransports\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aidatransports.com\\\/aidat2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AIDA Transports | Partenaires","description":"Ils nous ont fait confiance. Les partenaires d'AIDA Transports.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aidatransports.com\/aidat2024\/ils-nous-ont-fait-confiance\/","og_locale":"fr_FR","og_type":"article","og_title":"AIDA Transports | Partenaires","og_description":"Ils nous ont fait confiance. Les partenaires d'AIDA Transports.","og_url":"https:\/\/aidatransports.com\/aidat2024\/ils-nous-ont-fait-confiance\/","og_site_name":"aidatransports","article_modified_time":"2026-05-06T07:38:35+00:00","og_image":[{"width":1200,"height":382,"url":"https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/Groupe-Mendy.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aidatransports.com\/aidat2024\/ils-nous-ont-fait-confiance\/","url":"https:\/\/aidatransports.com\/aidat2024\/ils-nous-ont-fait-confiance\/","name":"AIDA Transports | Partenaires","isPartOf":{"@id":"https:\/\/aidatransports.com\/aidat2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aidatransports.com\/aidat2024\/ils-nous-ont-fait-confiance\/#primaryimage"},"image":{"@id":"https:\/\/aidatransports.com\/aidat2024\/ils-nous-ont-fait-confiance\/#primaryimage"},"thumbnailUrl":"https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/Groupe-Mendy-1024x326.png","datePublished":"2024-03-21T09:55:58+00:00","dateModified":"2026-05-06T07:38:35+00:00","description":"Ils nous ont fait confiance. Les partenaires d'AIDA Transports.","breadcrumb":{"@id":"https:\/\/aidatransports.com\/aidat2024\/ils-nous-ont-fait-confiance\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aidatransports.com\/aidat2024\/ils-nous-ont-fait-confiance\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aidatransports.com\/aidat2024\/ils-nous-ont-fait-confiance\/#primaryimage","url":"https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/Groupe-Mendy.png","contentUrl":"https:\/\/aidatransports.com\/aidat2024\/wp-content\/uploads\/2026\/05\/Groupe-Mendy.png","width":1200,"height":382},{"@type":"BreadcrumbList","@id":"https:\/\/aidatransports.com\/aidat2024\/ils-nous-ont-fait-confiance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/aidatransports.com\/aidat2024\/"},{"@type":"ListItem","position":2,"name":"Ils nous ont fait confiance"}]},{"@type":"WebSite","@id":"https:\/\/aidatransports.com\/aidat2024\/#website","url":"https:\/\/aidatransports.com\/aidat2024\/","name":"aidatransports","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aidatransports.com\/aidat2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/aidatransports.com\/aidat2024\/wp-json\/wp\/v2\/pages\/770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aidatransports.com\/aidat2024\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aidatransports.com\/aidat2024\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aidatransports.com\/aidat2024\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aidatransports.com\/aidat2024\/wp-json\/wp\/v2\/comments?post=770"}],"version-history":[{"count":184,"href":"https:\/\/aidatransports.com\/aidat2024\/wp-json\/wp\/v2\/pages\/770\/revisions"}],"predecessor-version":[{"id":2244,"href":"https:\/\/aidatransports.com\/aidat2024\/wp-json\/wp\/v2\/pages\/770\/revisions\/2244"}],"wp:attachment":[{"href":"https:\/\/aidatransports.com\/aidat2024\/wp-json\/wp\/v2\/media?parent=770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}